{"id":648,"count":0,"description":"","link":"https:\/\/markatoonline.com\/am-et\/product-category\/%e1%8b%8d%e1%89%a0%e1%89%b5-%e1%8a%a5%e1%8a%93-%e1%8c%a4%e1%8a%93\/%e1%8b%8d%e1%89%a0%e1%89%b5\/%e1%8b%a8%e1%8a%a0%e1%8b%ad%e1%8a%95-%e1%88%9d%e1%88%ad%e1%89%b6%e1%89%bd\/","name":"\u12a0\u12ed\u1296\u127d","slug":"%e1%8b%a8%e1%8a%a0%e1%8b%ad%e1%8a%95-%e1%88%9d%e1%88%ad%e1%89%b6%e1%89%bd","taxonomy":"product_cat","parent":654,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u12a0\u12ed\u1296\u127d | Markato Online<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/markatoonline.com\/am-et\/product-category\/\u12cd\u1260\u1275-\u12a5\u1293-\u1324\u1293\/\u12cd\u1260\u1275\/\u12e8\u12a0\u12ed\u1295-\u121d\u122d\u1276\u127d\/\" \/>\n<meta property=\"og:locale\" content=\"am_ET\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u12a0\u12ed\u1296\u127d | Markato Online\" \/>\n<meta property=\"og:url\" content=\"https:\/\/markatoonline.com\/am-et\/product-category\/\u12cd\u1260\u1275-\u12a5\u1293-\u1324\u1293\/\u12cd\u1260\u1275\/\u12e8\u12a0\u12ed\u1295-\u121d\u122d\u1276\u127d\/\" \/>\n<meta property=\"og:site_name\" content=\"Markato Online\" \/>\n<meta property=\"og:image\" content=\"https:\/\/markatoonline.com\/wp-content\/uploads\/2025\/12\/Markato-Logo-Hero-1-scaled.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1429\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/markatoonline.com\\\/am-et\\\/product-category\\\/%e1%8b%8d%e1%89%a0%e1%89%b5-%e1%8a%a5%e1%8a%93-%e1%8c%a4%e1%8a%93\\\/%e1%8b%8d%e1%89%a0%e1%89%b5\\\/%e1%8b%a8%e1%8a%a0%e1%8b%ad%e1%8a%95-%e1%88%9d%e1%88%ad%e1%89%b6%e1%89%bd\\\/\",\"url\":\"https:\\\/\\\/markatoonline.com\\\/am-et\\\/product-category\\\/%e1%8b%8d%e1%89%a0%e1%89%b5-%e1%8a%a5%e1%8a%93-%e1%8c%a4%e1%8a%93\\\/%e1%8b%8d%e1%89%a0%e1%89%b5\\\/%e1%8b%a8%e1%8a%a0%e1%8b%ad%e1%8a%95-%e1%88%9d%e1%88%ad%e1%89%b6%e1%89%bd\\\/\",\"name\":\"\u12a0\u12ed\u1296\u127d | Markato Online\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/markatoonline.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/markatoonline.com\\\/am-et\\\/product-category\\\/%e1%8b%8d%e1%89%a0%e1%89%b5-%e1%8a%a5%e1%8a%93-%e1%8c%a4%e1%8a%93\\\/%e1%8b%8d%e1%89%a0%e1%89%b5\\\/%e1%8b%a8%e1%8a%a0%e1%8b%ad%e1%8a%95-%e1%88%9d%e1%88%ad%e1%89%b6%e1%89%bd\\\/#breadcrumb\"},\"inLanguage\":\"am-ET\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/markatoonline.com\\\/am-et\\\/product-category\\\/%e1%8b%8d%e1%89%a0%e1%89%b5-%e1%8a%a5%e1%8a%93-%e1%8c%a4%e1%8a%93\\\/%e1%8b%8d%e1%89%a0%e1%89%b5\\\/%e1%8b%a8%e1%8a%a0%e1%8b%ad%e1%8a%95-%e1%88%9d%e1%88%ad%e1%89%b6%e1%89%bd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/markatoonline.com\\\/am-et\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u12cd\u1260\u1275 \u12a5\u1293 \u1324\u1293\",\"item\":\"https:\\\/\\\/markatoonline.com\\\/am-et\\\/product-category\\\/%e1%8b%8d%e1%89%a0%e1%89%b5-%e1%8a%a5%e1%8a%93-%e1%8c%a4%e1%8a%93\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u12cd\u1260\u1275\",\"item\":\"https:\\\/\\\/markatoonline.com\\\/am-et\\\/product-category\\\/%e1%8b%8d%e1%89%a0%e1%89%b5-%e1%8a%a5%e1%8a%93-%e1%8c%a4%e1%8a%93\\\/%e1%8b%8d%e1%89%a0%e1%89%b5\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u12a0\u12ed\u1296\u127d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/markatoonline.com\\\/#website\",\"url\":\"https:\\\/\\\/markatoonline.com\\\/\",\"name\":\"Markato Online\",\"description\":\"Shopping joy, one tap away\",\"publisher\":{\"@id\":\"https:\\\/\\\/markatoonline.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/markatoonline.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"am-ET\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/markatoonline.com\\\/#organization\",\"name\":\"Markato Online\",\"url\":\"https:\\\/\\\/markatoonline.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"am-ET\",\"@id\":\"https:\\\/\\\/markatoonline.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/markatoonline.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cropped-cropped-vendor-profile-photo001.png\",\"contentUrl\":\"https:\\\/\\\/markatoonline.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cropped-cropped-vendor-profile-photo001.png\",\"width\":384,\"height\":384,\"caption\":\"Markato Online\"},\"image\":{\"@id\":\"https:\\\/\\\/markatoonline.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/@markatoonline\",\"https:\\\/\\\/www.instagram.com\\\/onlinemarkato\",\"https:\\\/\\\/www.tiktok.com\\\/@markatoonline\",\"https:\\\/\\\/www.youtube.com\\\/@MarkatoOnline\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u12a0\u12ed\u1296\u127d | Markato Online","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/markatoonline.com\/am-et\/product-category\/\u12cd\u1260\u1275-\u12a5\u1293-\u1324\u1293\/\u12cd\u1260\u1275\/\u12e8\u12a0\u12ed\u1295-\u121d\u122d\u1276\u127d\/","og_locale":"am_ET","og_type":"article","og_title":"\u12a0\u12ed\u1296\u127d | Markato Online","og_url":"https:\/\/markatoonline.com\/am-et\/product-category\/\u12cd\u1260\u1275-\u12a5\u1293-\u1324\u1293\/\u12cd\u1260\u1275\/\u12e8\u12a0\u12ed\u1295-\u121d\u122d\u1276\u127d\/","og_site_name":"Markato Online","og_image":[{"width":2560,"height":1429,"url":"https:\/\/markatoonline.com\/wp-content\/uploads\/2025\/12\/Markato-Logo-Hero-1-scaled.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/markatoonline.com\/am-et\/product-category\/%e1%8b%8d%e1%89%a0%e1%89%b5-%e1%8a%a5%e1%8a%93-%e1%8c%a4%e1%8a%93\/%e1%8b%8d%e1%89%a0%e1%89%b5\/%e1%8b%a8%e1%8a%a0%e1%8b%ad%e1%8a%95-%e1%88%9d%e1%88%ad%e1%89%b6%e1%89%bd\/","url":"https:\/\/markatoonline.com\/am-et\/product-category\/%e1%8b%8d%e1%89%a0%e1%89%b5-%e1%8a%a5%e1%8a%93-%e1%8c%a4%e1%8a%93\/%e1%8b%8d%e1%89%a0%e1%89%b5\/%e1%8b%a8%e1%8a%a0%e1%8b%ad%e1%8a%95-%e1%88%9d%e1%88%ad%e1%89%b6%e1%89%bd\/","name":"\u12a0\u12ed\u1296\u127d | Markato Online","isPartOf":{"@id":"https:\/\/markatoonline.com\/#website"},"breadcrumb":{"@id":"https:\/\/markatoonline.com\/am-et\/product-category\/%e1%8b%8d%e1%89%a0%e1%89%b5-%e1%8a%a5%e1%8a%93-%e1%8c%a4%e1%8a%93\/%e1%8b%8d%e1%89%a0%e1%89%b5\/%e1%8b%a8%e1%8a%a0%e1%8b%ad%e1%8a%95-%e1%88%9d%e1%88%ad%e1%89%b6%e1%89%bd\/#breadcrumb"},"inLanguage":"am-ET"},{"@type":"BreadcrumbList","@id":"https:\/\/markatoonline.com\/am-et\/product-category\/%e1%8b%8d%e1%89%a0%e1%89%b5-%e1%8a%a5%e1%8a%93-%e1%8c%a4%e1%8a%93\/%e1%8b%8d%e1%89%a0%e1%89%b5\/%e1%8b%a8%e1%8a%a0%e1%8b%ad%e1%8a%95-%e1%88%9d%e1%88%ad%e1%89%b6%e1%89%bd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/markatoonline.com\/am-et\/"},{"@type":"ListItem","position":2,"name":"\u12cd\u1260\u1275 \u12a5\u1293 \u1324\u1293","item":"https:\/\/markatoonline.com\/am-et\/product-category\/%e1%8b%8d%e1%89%a0%e1%89%b5-%e1%8a%a5%e1%8a%93-%e1%8c%a4%e1%8a%93\/"},{"@type":"ListItem","position":3,"name":"\u12cd\u1260\u1275","item":"https:\/\/markatoonline.com\/am-et\/product-category\/%e1%8b%8d%e1%89%a0%e1%89%b5-%e1%8a%a5%e1%8a%93-%e1%8c%a4%e1%8a%93\/%e1%8b%8d%e1%89%a0%e1%89%b5\/"},{"@type":"ListItem","position":4,"name":"\u12a0\u12ed\u1296\u127d"}]},{"@type":"WebSite","@id":"https:\/\/markatoonline.com\/#website","url":"https:\/\/markatoonline.com\/","name":"Markato Online","description":"Shopping joy, one tap away","publisher":{"@id":"https:\/\/markatoonline.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/markatoonline.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"am-ET"},{"@type":"Organization","@id":"https:\/\/markatoonline.com\/#organization","name":"Markato Online","url":"https:\/\/markatoonline.com\/","logo":{"@type":"ImageObject","inLanguage":"am-ET","@id":"https:\/\/markatoonline.com\/#\/schema\/logo\/image\/","url":"https:\/\/markatoonline.com\/wp-content\/uploads\/2025\/10\/cropped-cropped-vendor-profile-photo001.png","contentUrl":"https:\/\/markatoonline.com\/wp-content\/uploads\/2025\/10\/cropped-cropped-vendor-profile-photo001.png","width":384,"height":384,"caption":"Markato Online"},"image":{"@id":"https:\/\/markatoonline.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/@markatoonline","https:\/\/www.instagram.com\/onlinemarkato","https:\/\/www.tiktok.com\/@markatoonline","https:\/\/www.youtube.com\/@MarkatoOnline"]}]}},"_links":{"self":[{"href":"https:\/\/markatoonline.com\/am-et\/wp-json\/wp\/v2\/product_cat\/648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/markatoonline.com\/am-et\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/markatoonline.com\/am-et\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/markatoonline.com\/am-et\/wp-json\/wp\/v2\/product_cat\/654"}],"wp:post_type":[{"href":"https:\/\/markatoonline.com\/am-et\/wp-json\/wp\/v2\/product?product_cat=648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}